{"id":850,"date":"2023-10-31T15:26:23","date_gmt":"2023-10-31T15:26:23","guid":{"rendered":"https:\/\/mojiedit.com\/?page_id=850"},"modified":"2023-10-31T15:26:55","modified_gmt":"2023-10-31T15:26:55","slug":"politica-de-diversidade","status":"publish","type":"page","link":"https:\/\/mojiedit.com\/pt\/diversity-policy\/","title":{"rendered":"Pol\u00edtica de diversidade"},"content":{"rendered":"<div class=\"markdown markdown-main-panel\" dir=\"ltr\">\n<h2 data-sourcepos=\"1:1-1:42\"><strong>Pol\u00edtica de diversidade para conte\u00fado editorial<\/strong><\/h2>\n<p data-sourcepos=\"3:1-3:130\">O Mojiedit.com tem o compromisso de promover a diversidade e a inclus\u00e3o em nosso conte\u00fado editorial. Acreditamos que a diversidade \u00e9 essencial para criar um reflexo mais preciso e representativo do mundo ao nosso redor.<\/p>\n<p data-sourcepos=\"5:1-5:107\">N\u00f3s nos esfor\u00e7amos para incluir diversas vozes e perspectivas em nosso conte\u00fado editorial, incluindo, mas n\u00e3o se limitando a:<\/p>\n<ul data-sourcepos=\"7:1-14:0\">\n<li data-sourcepos=\"7:1-7:20\">Ra\u00e7a e etnia<\/li>\n<li data-sourcepos=\"8:1-8:8\">G\u00eanero<\/li>\n<li data-sourcepos=\"9:1-9:20\">Orienta\u00e7\u00e3o sexual<\/li>\n<li data-sourcepos=\"10:1-10:5\">Idade<\/li>\n<li data-sourcepos=\"11:1-11:12\">Defici\u00eancia<\/li>\n<li data-sourcepos=\"12:1-12:22\">Status socioecon\u00f4mico<\/li>\n<li data-sourcepos=\"13:1-14:0\">Localiza\u00e7\u00e3o geogr\u00e1fica<\/li>\n<\/ul>\n<p data-sourcepos=\"15:1-15:14\"><span class=\"animating\">Tamb\u00e9m nos esfor\u00e7amos para evitar <\/span><span class=\"citation-0 citation-end-0 animating\">estere\u00f3tipos e preconceitos em nosso conte\u00fado editorial. Promovemos retratos justos e precisos de indiv\u00edduos e grupos, desafiando narrativas prejudiciais e concep\u00e7\u00f5es err\u00f4neas.<\/span><\/p>\n<p data-sourcepos=\"17:1-17:13\">Aqui est\u00e3o algumas maneiras espec\u00edficas de promover a diversidade e a inclus\u00e3o em nosso conte\u00fado editorial:<\/p>\n<ul data-sourcepos=\"19:1-23:0\">\n<li data-sourcepos=\"19:1-19:103\">Temos uma equipe diversificada de editores e redatores que v\u00eam de v\u00e1rias forma\u00e7\u00f5es e experi\u00eancias.<\/li>\n<li data-sourcepos=\"20:1-20:80\">Buscamos ativamente e publicamos hist\u00f3rias de diversas vozes e perspectivas.<\/li>\n<li data-sourcepos=\"21:1-21:132\">Trabalhamos com nossos editores e redatores para garantir que seu conte\u00fado seja justo e preciso e que evite estere\u00f3tipos e preconceitos.<\/li>\n<li data-sourcepos=\"22:1-23:0\">Temos um processo de feedback em vigor para que nossos leitores possam nos fornecer feedback sobre nossos esfor\u00e7os de diversidade.<\/li>\n<\/ul>\n<p data-sourcepos=\"24:1-24:165\">Acreditamos que a diversidade e a inclus\u00e3o s\u00e3o essenciais para a cria\u00e7\u00e3o de conte\u00fado editorial de alta qualidade. Temos o compromisso de promover a diversidade e a inclus\u00e3o em todo o nosso trabalho.<\/p>\n<p data-sourcepos=\"26:1-26:52\"><strong class=\"animating\">Como fornecer feedback sobre nossos esfor\u00e7os de diversidade<\/strong><\/p>\n<p data-sourcepos=\"28:1-28:216\"><span class=\"animating\">Se voc\u00ea tiver algum feedback sobre nossos esfor\u00e7os de diversidade,<\/span><span class=\"animating\"> use nosso <a href=\"https:\/\/mojiedit.com\/pt\/entre-em-contato-conosco\/\">p\u00e1gina de contato<\/a><\/span><span class=\"animating\">.<\/span><span class=\"animating\"> Agradecemos seu feedback e o utilizaremos para aprimorar nossas pol\u00edticas e pr\u00e1ticas de diversidade e inclus\u00e3o.<\/span><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de diversidade para conte\u00fado editorial O Mojiedit.com tem o compromisso de promover a diversidade e a inclus\u00e3o em nosso conte\u00fado editorial. Acreditamos que<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"class_list":["post-850","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/pages\/850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/comments?post=850"}],"version-history":[{"count":0,"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/pages\/850\/revisions"}],"wp:attachment":[{"href":"https:\/\/mojiedit.com\/pt\/wp-json\/wp\/v2\/media?parent=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}